{"id":163,"date":"2015-12-02T10:17:59","date_gmt":"2015-12-02T10:17:59","guid":{"rendered":"http:\/\/develop.inicianet.eu:9092\/?page_id=163"},"modified":"2025-07-29T12:33:27","modified_gmt":"2025-07-29T11:33:27","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/delgadozuleta.com\/en\/terminos-y-condiciones\/","title":{"rendered":"Terms and Conditions"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-c82d39c6 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-64fc7c7a\"><h2 class=\"uagb-heading-text\">T\u00c9RMINOS Y CONDICIONES<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2eee7cc5\"><h2 class=\"uagb-heading-text\">ACEPTACI\u00d3N Y DISPONIBILIDAD DE LAS CONDICIONES GENERALES DE CONTRATACI\u00d3N<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-88bc27ae alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p>Las presentes condiciones generales de contrataci\u00f3n, en adelante, \u00abLas Condiciones Generales\u00bb, regular\u00e1n las relaciones que pueden surgir entre DELGADO ZULETA S.A. (en adelante, el prestador) y los usuarios- clientes, en adelante, \u00ablos Clientes\u00bb, que contraten la prestaci\u00f3n de los servicios o productos ofertados a trav\u00e9s del sitio web.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"txt\">La aceptaci\u00f3n del presente documento tiene la misma validez contractual que la firma presencial del mismo. El hecho de seguir telem\u00e1ticamente todos los pasos descritos en el procedimiento de contrataci\u00f3n, supone la presunci\u00f3n de que el usuario acepta inequ\u00edvocamente las presentes condiciones generales de contrataci\u00f3n. Este documento puede ser impreso y almacenado por los Clientes. www.delgadozuleta.com pone a disposici\u00f3n de estos, la direcci\u00f3n de e-mail <a class=\"link\" href=\"mailto:tienda@delgadozuleta.com\">tienda@delgadozuleta.com<\/a> para que puedan plantear cualquier duda acerca de las Condiciones Generales.<\/p>\n\n\n\n<p class=\"txt\">El prestador, con el fin de mejorar los servicios y productos ofrecidos, se reserva el derecho de modificar en cualquier momento las presentes condiciones, as\u00ed como cualquier otro documento expuesto en el sitio web, notific\u00e1ndolo a los Clientes con antelaci\u00f3n suficiente.<\/p>\n\n\n\n<p class=\"txt\">El idioma de formalizaci\u00f3n del contrato est\u00e1 redactado en espa\u00f1ol.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">2. LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h2>\n\n\n\n<p>Las presentes Condiciones han sido elaboradas de conformidad con lo establecido en la Ley 34\/2002, de servicios de la sociedad de la informaci\u00f3n y comercio electr\u00f3nico, la Ley 7\/1998 sobre Condiciones Generales de Contrataci\u00f3n, el Real Decreto 1906\/1999 por el que se regula la contrataci\u00f3n telef\u00f3nica o electr\u00f3nica con condiciones generales en desarrollo del art\u00edculo 5.3 de la Ley 7\/1998, el Real Decreto Legislativo 1\/2007, de 16 de noviembre, por el que se aprueba el Texto Refundido de la Ley General de Defensa de los Consumidores y Clientes y otras leyes complementarias, la Ley 7\/1996 de Ordenaci\u00f3n del Comercio Minorista, el Real Decreto-Ley 14\/1999 reguladora de la Firma Electr\u00f3nica y cuantas disposiciones legales resulten de aplicaci\u00f3n.\n\nPara toda cuesti\u00f3n litigiosa o que incumba a las presentes Condiciones Generales alojadas en www.delgadozuleta.com ser\u00e1 de aplicaci\u00f3n la legislaci\u00f3n espa\u00f1ola, siendo competentes para la resoluci\u00f3n de todos los conflictos derivados o relacionados con las presentes condiciones, los Juzgados y Tribunales espa\u00f1oles situados en la direcci\u00f3n fiscal de DELGADO ZULETA S.A.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">3. PRODUCTOS<\/h2>\n\n\n\n<p class=\"txt\">Los Productos ofertados en DELGADO ZULETA S.A., junto con sus caracter\u00edsticas esenciales y precio aparecer\u00e1n en pantalla. Aparte del precio, y antes de confirmar el pedido, aparecer\u00e1n en pantalla el total de los gastos de env\u00edo al domicilio del Cliente. Las ofertas estar\u00e1n debidamente indicadas en pantalla.<\/p>\n\n\n\n<p class=\"txt\">DELGADO ZULETA S.A.hace todos los esfuerzos dentro de sus medios para ofrecer la informaci\u00f3n contenida en el website de forma veraz y sin errores tipogr\u00e1ficos. En el caso que en alg\u00fan momento se produjera alg\u00fan error de este tipo, ajeno en todo momento a la voluntad de DELGADO ZULETA S.A. se proceder\u00eda inmediatamente a su correcci\u00f3n.<\/p>\n\n\n\n<p class=\"txt\">En el caso de que, una vez realizado el pedido, DELGADO ZULETA S.A. no disponga de stock de alguno de los producto\/s solicitado\/s se informar\u00e1 al cliente de dicha falta de disponibilidad y se proceder\u00e1 a la cancelaci\u00f3n del pedido reintegrando las sumas abonadas correspondientes a dicho producto\/s no disponible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">4. PRECIOS<\/h2>\n\n\n\n<p class=\"txt\">El precio de nuestros art\u00edculos y servicios es el que se indica en cada momento en nuestro sitio web. Los precios de los Productos se muestran siempre en euros e incluyen el IVA y cualquier otro impuesto que fuera de aplicaci\u00f3n, y ser\u00e1n en todo momento los vigentes.<\/p>\n\n\n\n<p class=\"txt\">Si DELGADO ZULETA S.A. detectase que ha existido un error en la introducci\u00f3n del precio de un art\u00edculo, con posterioridad a la recepci\u00f3n de un pedido, nos pondremos en contacto con Ud lo antes posible para informarle de la incidencia, y ofrecerle la opci\u00f3n de cancelaci\u00f3n o mantenimiento en las condiciones correctas. La remisi\u00f3n de confirmaci\u00f3n autom\u00e1tica no valida condiciones de precio err\u00f3neas. En caso de cancelaci\u00f3n le ser\u00e1 reintegrada cualquier cantidad que hubiese sido abonada. Sin su expresa conformidad a las condiciones de precio correctas, no se proceder\u00e1 a dar curso al env\u00edo.<\/p>\n\n\n\n<p class=\"txt\">El precio del producto no incluye los gastos de env\u00edo. Estos gastos corren por cuenta del Cliente y se a\u00f1adir\u00e1n al total del importe de los Productos seleccionados. El coste del servicio de entrega contratado vendr\u00e1 determinado por las condiciones y modalidad de dicho servicio seleccionadas. Se informar\u00e1 al Cliente debidamente de dichos costes, que ser\u00e1n debidamente desglosados previamente a la realizaci\u00f3n del pago antes de confirmar el pedido y finalizar el proceso de contrataci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">5. M\u00c9TODOS DE COMPRA Y PAGOS<\/h2>\n\n\n\n<p class=\"txt\">Comprar en nuestra tienda es muy sencillo: s\u00f3lo tiene que elegir un art\u00edculo, incorporarlo a la cesta pulsando sobre el icono del carrito y tramitar el pedido, empleando el medio de pago que prefiera.<\/p>\n\n\n\n<p class=\"txt\">Acto seguido, el comprador recibir\u00e1 un correo electr\u00f3nico en el que se mostrar\u00e1 toda la informaci\u00f3n relativa a su compra. Este documento es la confirmaci\u00f3n de que la compra se ha realizado con \u00e9xito y cuenta con valor probatorio pleno ante cualquier tipo de reclamaci\u00f3n, siempre y cuando se adjunte el justificante del pago correspondiente. En caso de no recibir dicho correo electr\u00f3nico revise su cuenta de \u00abcorreo no deseado\u00bb o \u00abantispam\u00bb, ya que puede haber sido detectado como spam, si no se encuentra en dicho apartado, le rogamos nos lo comunique en el menor espacio de tiempo posible al Servicio de Atenci\u00f3n al Cliente mediante correo electr\u00f3nico a la direcci\u00f3n <a class=\"link\" href=\"mailto:tienda@delgadozuleta.com\">tienda@delgadozuleta.com<\/a> para que podamos solucionar el problema.<\/p>\n\n\n\n<p class=\"txt\">DELGADO ZULETA S.A. no enviar\u00e1 ning\u00fan producto hasta que su departamento de administraci\u00f3n haya comprobado que se ha realizado el pago con el fin de evitar posibles pedidos falsos o no aceptados por el cliente.<\/p>\n\n\n\n<p class=\"txt\">En caso de impago por el Cliente, total o parcial, en la fecha de vencimiento pactada para uno o m\u00e1s env\u00edos de productos, DELGADO ZULETA S.A. podr\u00e1 suspender o cancelar cualquier env\u00edo o Contrato pendiente, sin incurrir en responsabilidad por cualesquiera da\u00f1os o p\u00e9rdidas, incluido el lucro cesante, o da\u00f1os por retraso o p\u00e9rdida de producci\u00f3n ocasionados al Cliente. La anterior facultad de DELGADO ZULETA S.A. en ning\u00fan caso liberar\u00e1 al Cliente de sus obligaciones contractuales con relaci\u00f3n a los pagos adeudados y a la recepci\u00f3n de productos.<\/p>\n\n\n\n<p class=\"txt\">Si el pedido, una vez confirmado y enviado, no es aceptado por el cliente \u00e9ste deber\u00e1 hacerse cargo de los gastos ocasionados. Recibir\u00e1 una factura o justificante de compra por correo postal y\/o correo electr\u00f3nico. Todos los pedidos falsos, o intentos de fraude, ser\u00e1n denunciados ante las autoridades competentes. Se proporcionar\u00e1 toda la informaci\u00f3n necesaria para colaborar con la investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"txt\">En caso de producirse un retraso en la recepci\u00f3n o retirada de la mercanc\u00eda por parte del Cliente, DELGADO ZULETA S.A. quedar\u00e1 facultado para almacenar la mercanc\u00eda, por cuenta y riesgo del Cliente, en sus instalaciones o en las de un tercero y el cliente vendr\u00e1 obligado al pago de los gastos ocasionados a DELGADO ZULETA S.A.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtitle\">FORMAS DE PAGO<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><br><p class=\"txt\"><strong>Transferencia bancaria:<br><\/strong><\/p><br>El pago mediante transferencia puede incrementar el importe de su compra seg\u00fan las condiciones de su banco. Puede hacer una transferencia a la cuenta n\u00ba CAJA RURAL DEL SUR IBAN ES12 3187 0080 0420 1532 1827 y enviarnos un justificante de la transferencia al correo tienda@delgadozuleta.com para agilizar el env\u00edo junto con el n\u00famero de pedido. Si en el plazo de 48 h. no se realiza la transferencia, autom\u00e1ticamente se eliminar\u00e1 su pedido<\/li>\n\n\n\n<li><br><p class=\"txt\"><strong>Paypal:<br><\/strong><\/p><br>es el l\u00edder global en pagos en l\u00ednea y b\u00e1sicamente es un sistema de pago seguro en el cual el usuario abre una cuenta en el sistema que posteriormente le permite realizar pagos en multitud de tiendas en l\u00ednea alrededor del mundo, utilizando para ello su tarjeta de cr\u00e9dito o d\u00e9bito.<br>Paypal ser\u00e1 el \u00fanico que tendr\u00e1 sus datos bancarios siendo un intermediario ente usted y DELGADO ZULETA S.A. Esta forma de pago es inmediata, en el momento en el que usted realiza el pago, lo recibimos pasando a procesar su pedido (previa verificaci\u00f3n de que los datos son correctos).<br>Para darse de alta u obtener m\u00e1s informaci\u00f3n visite www.paypal.es, sitio de Paypal para Espa\u00f1a o <a class=\"link\" href=\"http:\/\/www.paypal.com\">www.paypal.com<\/a> sitio principal de Paypal (en ingl\u00e9s). Estos v\u00ednculos son externos y enlazan a p\u00e1ginas con sus propias condiciones de uso y\/o privacidad.<\/li>\n\n\n\n<li><strong>Tarjeta de Cr\u00e9dito.<\/strong> Puede pagar con su tarjeta Visa y Mastercard a trav\u00e9s de la pasarela de pago seguro.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading title\">6. ENV\u00cdOS<\/h2>\n\n\n\n<p class=\"txt\">El env\u00edo de los productos adquiridos se llevar\u00e1 a cabo seg\u00fan la forma seleccionada por el propio usuario entre las disponibles en el momento de la compra. Los plazos de entrega oscilan entre las 24 y las 72 horas. No podemos garantizar estos plazos de entrega, si bien intentamos que las empresas de transporte los cumplan siempre que sea posible.<\/p>\n\n\n\n<p class=\"txt\">El importe del transporte vendr\u00e1 incluido en la factura del cliente, y determinado por las tablas de pesos y distancias en nuestro apartado de transporte, que el cliente puede consultar.<\/p>\n\n\n\n<p class=\"txt\">El transportista ser\u00e1 el convenido por DELGADO ZULETA S.A. y del cual ser\u00e1 informado el cliente.\n\u00danicamente se realizan env\u00edos a Espa\u00f1a peninsular. No se suministran pedidos a los siguientes destinos: Canarias, Baleares, Ceuta y Melilla.\n<\/p>\n\n\n\n<p class=\"txt\">Se debe facilitar un tel\u00e9fono de contacto en el que se pueda localizar habitualmente al destinatario, para solucionar r\u00e1pidamente problemas con la preparaci\u00f3n del pedido y sobre todo, para agilizar la entrega. Si alg\u00fan dato es err\u00f3neo debes notific\u00e1rnoslo cuanto antes.<\/p>\n\n\n\n<p class=\"txt\">En cualquier caso, la empresa de mensajer\u00eda contactar\u00e1 telef\u00f3nicamente para acordar una nueva entrega en caso de ausencia.<\/p>\n\n\n\n<p class=\"txt\">Recuerde que puede solicitar que la direcci\u00f3n de entrega del pedido sea otra distinta a la de facturaci\u00f3n. Por ejemplo, para hacer un regalo, ind\u00edquenos en el campo reservado para ello que encontrar\u00e1 al formalizar su pedido y tampoco a\u00f1adiremos la factura en el interior del paquete.<\/p>\n\n\n\n<p class=\"txt\">Si el cliente aprecia roturas en el paquete, debe realizar una incidencia en el mismo albar\u00e1n en el momento de la entrega, indicando que el paquete viene roto y ponerse en contacto con DELGADO ZULETA S.A. para notificar dicha situaci\u00f3n.<\/p>\n\n\n\n<p class=\"txt\">Si el cliente no aprecia roturas externas en el paquete a la hora de recibirlo, pero al abrirlo observa desperfectos a causa del transporte, debe notificarlo en menos de 24 horas a la compa\u00f1\u00eda de transporte para dejar constancia y ponerse en contacto con DELGADO ZULETA S.A. En caso contrario se entender\u00e1 que el Producto ha sido aceptado de conformidad. La empresa de transporte una vez pasado este plazo considera que el material enviado est\u00e1 en perfecto estado y no se hace responsable de los desperfectos.<\/p>\n\n\n\n<p class=\"txt\">DELGADO ZULETA S.A. no se hace responsable de ning\u00fan retraso originado en el transporte por:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><br><p class=\"txt\">&#8211; Direcci\u00f3n incorrecta o incompleta<\/p><br><\/li>\n\n\n\n<li><br><p class=\"txt\">&#8211; No indicar un n\u00famero de tel\u00e9fono de contacto<\/p><br><\/li>\n\n\n\n<li><br><p class=\"txt\">&#8211; Huelgas de los transportistas<\/p><br><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading title\">7. GASTOS DE ENV\u00cdO<\/h2>\n\n\n\n<p class=\"txt\">Andaluc\u00eda. Gastos de transporte 5,30 \u20ac (1 caja de 1 botella o de 3 o de 6 o de 12); de 2 a 10 bultos, 4,70 \u20ac por bulto.<\/p>\n\n\n\n<p class=\"txt\">Zona Centro-Levante (Madrid, Arag\u00f3n, La Rioja, Extremadura, Castilla La Mancha, Castilla y Le\u00f3n, Murcia, Comunidad Valenciana). Gastos de transporte 6,20 \u20ac (1 caja de 1 botella o de 3 o de 6 o de 12); de 2 a 10 bultos, 4,70 \u20ac por bulto.<\/p>\n\n\n\n<p class=\"txt\">Zona Norte (Galicia, Asturias., Cantabria, Euskadi, Navarra, Catalu\u00f1a). Gastos de transporte 7,20 \u20ac (1 caja de 1 botella o de 3 o de 6 o de 12); de 2 a 10 bultos, 4,70 \u20ac por bulto.<\/p>\n\n\n\n<p class=\"txt\">Gratuitos en todos las compras a cualquiera de las 3 zonas anteriores superiores a 70 \u20ac.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">8. DEVOLUCIONES<\/h2>\n\n\n\n<p class=\"txt\">Conforme a la legislaci\u00f3n vigente, se puede proceder a la devoluci\u00f3n de productos, por el motivo que sea, en un plazo de 7 d\u00edas naturales desde la recepci\u00f3n de la mercanc\u00eda por el cliente. Para ello se deben cumplir las condiciones expuestas en esta p\u00e1gina de condiciones.<\/p>\n\n\n\n<p class=\"txt\">La devoluci\u00f3n incluir\u00e1 el importe de la compra y si hubieran existido, los costes de entrega, no obstante, en caso de que el Cliente haya seleccionado una modalidad de entrega diferente a la modalidad menos costosa de entrega ordinaria, DELGADO ZULETA S.A. \u00fanicamente abonar\u00e1 el importe correspondiente a una entrega ordinaria. La devoluci\u00f3n se realizar\u00e1 en el mismo medio de pago con el que el Producto fue adquirido, descont\u00e1ndose los costes de devoluci\u00f3n que correr\u00e1n a cargo del cliente.<\/p>\n\n\n\n<p class=\"txt\">El Cliente deber\u00e1 devolver los productos objeto de desistimiento sin ninguna demora indebida y en cualquier caso a m\u00e1s tardar en el plazo de 7 d\u00edas naturales a partir de la fecha en que se comunique su decisi\u00f3n de desistimiento.<\/p>\n\n\n\n<p class=\"txt\">La devoluci\u00f3n del importe correspondiente al desistimiento se realizar\u00e1 en un plazo de 7 d\u00edas naturales desde la fecha en que haya sido comunicada efectiva e inequ\u00edvocamente la decisi\u00f3n de desistimiento del contrato y siempre que se hayan recibido previamente los bienes o productos objeto de desistimiento, en caso contrario, podr\u00e1 retenerse el desembolso hasta la recepci\u00f3n de dichos bienes o hasta que el Cliente acredite la devoluci\u00f3n de los bienes.<\/p>\n\n\n\n<p class=\"txt\">Quedan excluidos del derecho de desistimiento: (i) La prestaci\u00f3n de servicios, una vez que el servicio haya sido completamente ejecutado. (ii) El suministro de bienes o prestaciones de servicios confeccionados conforme a las especificaciones del Cliente o claramente personalizados. (iii) El suministro de bienes precintados que no sean aptos para ser devueltos por razones de protecci\u00f3n de la salud o de higiene y que hayan sido desprecintados tras la entrega. (iv) El suministro de grabaciones sonoras o de v\u00eddeo precintadas o de programas inform\u00e1ticos precintados que hayan sido desprecintados por el Cliente despu\u00e9s de la entrega. (v) El suministro de contenido digital (que no se preste en un soporte material) cuando la ejecuci\u00f3n ya haya comenzado. El Cliente conoce expresamente que una vez comenzada la descarga digital perder\u00e1 el derecho de desistimiento. (vi) Cualquier otro bien o servicio amparado en el art. 103 del RDL 1\/2007, de 16 de noviembre.<\/p>\n\n\n\n<p class=\"txt\">El Cliente ser\u00e1 responsable de la disminuci\u00f3n de valor de los bienes resultante de una manipulaci\u00f3n de los mismos distinta a la necesaria para establecer su naturaleza, sus caracter\u00edsticas o su funcionamiento. En todo caso, a los efectos de hacer uso del derecho de desistimiento, es necesario que los Productos sean devueltos en sus embalajes originales junto con la factura, en el caso de que se devuelvan sin dichos embalajes originales o con desperfectos el importe que se abonar\u00e1 al Cliente por la devoluci\u00f3n del producto ser\u00e1 disminuido en la cantidad que corresponda. Antes de devolver el Producto, el Cliente debe asegurarse de que el mismo el mismo se encuentra debidamente protegido y precintado para que no sufra ning\u00fan da\u00f1o durante el transporte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtitle\">PRODUCTOS DEFECTUOSOS O ENV\u00cdOS ERR\u00d3NEOS:<\/h3>\n\n\n\n<p class=\"txt\">En caso de que el producto sea devuelto por falta de conformidad (productos defectuosos o env\u00edos err\u00f3neos), el usuario tendr\u00e1 derecho a optar bien por la devoluci\u00f3n de la cantidad econ\u00f3mica abonada o bien por la restituci\u00f3n del producto por otro de id\u00e9nticas caracter\u00edsticas. En dichos supuestos ser\u00e1 DELGADO ZULETA S.A. qui\u00e9n se har\u00e1 cargo de los gastos de env\u00edo o devoluci\u00f3n del producto.<\/p>\n\n\n\n<p class=\"txt\">El usuario dispone de 14 d\u00edas desde la entrega del producto para poder devolverlo, siendo requisito indispensable que se ponga en contacto en un plazo m\u00e1ximo de 48 horas desde la recepci\u00f3n del pedido con el departamento de atenci\u00f3n al cliente mediante correo electr\u00f3nico a la direcci\u00f3n, <a class=\"link\" href=\"mailto:tienda@delgadozuleta.com\">tienda@delgadozuleta.com<\/a> indicando el motivo de la devoluci\u00f3n. En caso de que no llevarse a cabo esta comunicaci\u00f3n previa no ser\u00e1 posible tramitar la devoluci\u00f3n.<\/p>\n\n\n\n<p class=\"txt\">La devoluci\u00f3n del importe, ser\u00e1 siempre realizada seg\u00fan la forma en la que el usuario hubiera abonado inicialmente la compra y siempre que se cumpla con los requisitos anteriormente indicados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtitle\">GARANTIAS<\/h3>\n\n\n\n<p class=\"txt\">Nuestros productos cuentan con las siguientes garant\u00edas:<\/p>\n\n\n\n<p class=\"txt\">Garant\u00eda de origen. Si en el momento de recibir su producto \u00e9ste se encontrase defectuoso ser\u00e1 reemplazado, de manera totalmente gratuita, por un nuevo producto, siempre que el producto no haya sido usado. Por decisi\u00f3n de DELGADO ZULETA S.A. y para determinados productos rebajados, se realizar\u00e1 una devoluci\u00f3n del importe en lugar de cambio, tras comprobar su estado. En caso de cambio ser\u00e1 necesario retornar la totalidad del material de origen y que la mercanc\u00eda no haya sido manipulada ni alterada, que se encuentre en perfecto estado y con todos sus pl\u00e1sticos protectores o embalajes originales.<\/p>\n\n\n\n<p class=\"txt\">Embale el producto en la medida de lo posible tal y como lo recibi\u00f3, para que no sufra da\u00f1os durante el transporte. No utilice cintas adhesivas ni escriba directamente sobre el embalaje original del producto. Es imprescindible que adjunte una copia de la factura o ticket de compra en el mismo. Enviaremos a la agencia de transporte a recoger el paquete y, una vez revisado el producto y comprobado el defecto, se proceder\u00e1 al env\u00edo de un nuevo producto al cliente en el menor plazo posible. En caso contrario (es decir, si el producto no presentase anomal\u00eda alguna) el cliente recibir\u00e1, otra vez, el mismo producto.<\/p>\n\n\n\n<p class=\"txt\">Importante: No se aceptar\u00e1 ning\u00fan producto que haya sufrido un desperfecto, en el embalaje o en el propio producto, Recomendamos no retirar los pl\u00e1sticos protectores si los hubiera hasta comprobar el perfecto funcionamiento de su art\u00edculo.<\/p>\n\n\n\n<p class=\"txt\">DELGADO ZULETA S.A. pone a disposici\u00f3n del usuario-cliente los siguientes datos para poder establecer un contacto r\u00e1pido, personal y directo con el objetivo de resolver cualquier cuesti\u00f3n, duda o queja: <a class=\"link\" href=\"mailto:tienda@delgadozuleta.com\">tienda@delgadozuleta.com<\/a> y <a class=\"link\" href=\"tel:+34956360543\">(+34) 956 360 543<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">9. EMPAQUETADO<\/h2>\n\n\n\n<p class=\"txt\">Los productos ir\u00e1n embalados de la mejor manera posible para garantizar su integridad durante el transporte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">10. CLAUSULA DE SALVAGUARDA<\/h2>\n\n\n\n<p class=\"txt\">Todas las cl\u00e1usulas o extremos del presente contrato deben ser interpretadas de forma independiente y aut\u00f3noma, no vi\u00e9ndose afectadas el resto de estipulaciones en caso de que una de ellas haya sido declarada NULA por sentencia judicial firme. Las partes contratantes acuerdan sustituir la cl\u00e1usula o cl\u00e1usulas afectadas por otra u otras que preserven los efectos perseguidos por las partes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading title\">11. EXONERACI\u00d3N DE RESPONSABILIDAD<\/h2>\n\n\n\n<p class=\"txt\">DELGADO ZULETA no responder\u00e1 por las interrupciones que se produzcan en los servicios el\u00e9ctricos o de telecomunicaciones que impidan a los clientes\/usuarios utilizar los servicios ofrecidos.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>T\u00c9RMINOS Y CONDICIONES ACEPTACI\u00d3N Y DISPONIBILIDAD DE LAS CONDICIONES GENERALES DE CONTRATACI\u00d3N Las presentes condiciones generales de contrataci\u00f3n, en adelante, [&hellip;]<\/p>\n","protected":false},"author":943,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-163","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y condiciones - Bodega Delgado Zuleta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delgadozuleta.com\/en\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones - Bodega Delgado Zuleta\" \/>\n<meta property=\"og:description\" content=\"T\u00c9RMINOS Y CONDICIONES ACEPTACI\u00d3N Y DISPONIBILIDAD DE LAS CONDICIONES GENERALES DE CONTRATACI\u00d3N Las presentes condiciones generales de contrataci\u00f3n, en adelante, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delgadozuleta.com\/en\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Bodega Delgado Zuleta\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T11:33:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/delgadozuleta.com\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y condiciones - Bodega Delgado Zuleta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#website\"},\"datePublished\":\"2015-12-02T10:17:59+00:00\",\"dateModified\":\"2025-07-29T11:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delgadozuleta.com\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/delgadozuleta.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#website\",\"url\":\"https:\\\/\\\/delgadozuleta.com\\\/\",\"name\":\"Bodega Delgado Zuleta\",\"description\":\"Hist\u00f3rica bodega del Marco de Jerez especialista en la elaboraci\u00f3n de vinos generosos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delgadozuleta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#organization\",\"name\":\"Bodega Delgado Zuleta\",\"url\":\"https:\\\/\\\/delgadozuleta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delgadozuleta.com\\\/wp-content\\\/uploads\\\/logo-transparente-300x133-1.png\",\"contentUrl\":\"https:\\\/\\\/delgadozuleta.com\\\/wp-content\\\/uploads\\\/logo-transparente-300x133-1.png\",\"width\":900,\"height\":400,\"caption\":\"Bodega Delgado Zuleta\"},\"image\":{\"@id\":\"https:\\\/\\\/delgadozuleta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones - Bodega Delgado Zuleta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delgadozuleta.com\/en\/terminos-y-condiciones\/","og_locale":"en_US","og_type":"article","og_title":"T\u00e9rminos y condiciones - Bodega Delgado Zuleta","og_description":"T\u00c9RMINOS Y CONDICIONES ACEPTACI\u00d3N Y DISPONIBILIDAD DE LAS CONDICIONES GENERALES DE CONTRATACI\u00d3N Las presentes condiciones generales de contrataci\u00f3n, en adelante, [&hellip;]","og_url":"https:\/\/delgadozuleta.com\/en\/terminos-y-condiciones\/","og_site_name":"Bodega Delgado Zuleta","article_modified_time":"2025-07-29T11:33:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delgadozuleta.com\/terminos-y-condiciones\/","url":"https:\/\/delgadozuleta.com\/terminos-y-condiciones\/","name":"T\u00e9rminos y condiciones - Bodega Delgado Zuleta","isPartOf":{"@id":"https:\/\/delgadozuleta.com\/#website"},"datePublished":"2015-12-02T10:17:59+00:00","dateModified":"2025-07-29T11:33:27+00:00","breadcrumb":{"@id":"https:\/\/delgadozuleta.com\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delgadozuleta.com\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/delgadozuleta.com\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/delgadozuleta.com\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones"}]},{"@type":"WebSite","@id":"https:\/\/delgadozuleta.com\/#website","url":"https:\/\/delgadozuleta.com\/","name":"Bodega Delgado Zuleta","description":"Hist\u00f3rica bodega del Marco de Jerez especialista en la elaboraci\u00f3n de vinos generosos.","publisher":{"@id":"https:\/\/delgadozuleta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delgadozuleta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/delgadozuleta.com\/#organization","name":"Bodega Delgado Zuleta","url":"https:\/\/delgadozuleta.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/delgadozuleta.com\/#\/schema\/logo\/image\/","url":"https:\/\/delgadozuleta.com\/wp-content\/uploads\/logo-transparente-300x133-1.png","contentUrl":"https:\/\/delgadozuleta.com\/wp-content\/uploads\/logo-transparente-300x133-1.png","width":900,"height":400,"caption":"Bodega Delgado Zuleta"},"image":{"@id":"https:\/\/delgadozuleta.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"BSINFOR EDUARDO","author_link":"https:\/\/delgadozuleta.com\/en\/blog\/author\/bsinfor\/"},"uagb_comment_info":0,"uagb_excerpt":"T\u00c9RMINOS Y CONDICIONES ACEPTACI\u00d3N Y DISPONIBILIDAD DE LAS CONDICIONES GENERALES DE CONTRATACI\u00d3N Las presentes condiciones generales de contrataci\u00f3n, en adelante, [&hellip;]","_links":{"self":[{"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/pages\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/users\/943"}],"replies":[{"embeddable":true,"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":11,"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/pages\/163\/revisions"}],"predecessor-version":[{"id":12774,"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/pages\/163\/revisions\/12774"}],"wp:attachment":[{"href":"https:\/\/delgadozuleta.com\/en\/wp-json\/wp\/v2\/media?parent=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}